{"id":321,"date":"2018-03-15T08:52:11","date_gmt":"2018-03-15T08:52:11","guid":{"rendered":"https:\/\/ikgeefgeluk.be\/?page_id=321"},"modified":"2020-04-20T11:20:54","modified_gmt":"2020-04-20T11:20:54","slug":"candidate-donneuse-dovocytes","status":"publish","type":"page","link":"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/","title":{"rendered":"Candidate-donneuse d&rsquo;ovocytes ?"},"content":{"rendered":"<ul>\n<li>Vous connaissez des couples qui souffrent de probl\u00e8mes de fertilit\u00e9 ?<\/li>\n<li>Vous aimeriez les aider pour qu\u2019ils puissent eux aussi conna\u00eetre le bonheur d\u2019\u00eatre parents ?<\/li>\n<li>C\u2019est possible, en devenant candidate-donneuse d\u2019ovocytes.<\/li>\n<\/ul>\n<h4>\u00c0 quelles conditions une candidate-donneuse d\u2019ovocytes doit-elle r\u00e9pondre ?<\/h4>\n<p> En tant que candidate-donneuse, vous devez remplir un certain nombre de conditions : <\/p>\n<ul>\n<li>Vous \u00eates \u00e2g\u00e9es de 21 \u00e0 35 ans.<\/li>\n<li>Vous habitez en Belgique.<\/li>\n<li>Vous ne souffrez pas de probl\u00e8mes de sant\u00e9.<\/li>\n<li>Il n\u2019y a pas de maladies g\u00e9n\u00e9tiques dans votre famille. Tous ces \u00e9l\u00e9ments sont v\u00e9rifi\u00e9s \u00e0 l\u2019aide d\u2019un questionnaire et lors de la consultation chez le m\u00e9decin.<\/li>\n<\/ul>\n<p> Veuillez noter que le don d\u2019ovocytes peut comporter <a href=\"http:\/\/ikgeefgeluk.be\/fr\/information-sur-le-don-dovocytes\/comment-se-deroule-un don-ovocytes\" target=\"_blank\" rel=\"noopener\">des risques et des effets secondaires<\/a>. Selon la l\u00e9gislation belge, le don d\u2019ovocytes est, en principe, <a href=\"http:\/\/ikgeefgeluk.be\/fr\/information-sur-le-don-dovocytes\/don-ovocytes-anonyme-don-ovocytes-connu\" target=\"_blank\" rel=\"noopener\">anonyme<\/a>. Cela signifie que ni la donneuse, ni les parents en attente et leur(s) enfant(s) ne re\u00e7oivent d\u2019informations les uns sur les autres. Le centre de fertilit\u00e9 ne peut en aucun cas transmettre des donn\u00e9es aux diff\u00e9rentes parties. <a href=\"http:\/\/ikgeefgeluk.be\/fr\/information-sur-le-don-dovocytes\/don-ovocytes-anonyme-don-ovocytes-connu\" target=\"_blank\" rel=\"noopener\">Le don connu<\/a> est \u00e9galement possible. Dans ce cas, le donneur et les parents demandeurs se connaissent et d\u00e9cident ensemble de ce qu\u2019ils diront \u00e0 l\u2019enfant et quand.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous connaissez des couples qui souffrent de probl\u00e8mes de fertilit\u00e9 ? Vous aimeriez les aider pour qu\u2019ils puissent eux aussi conna\u00eetre le bonheur d\u2019\u00eatre parents ? C\u2019est possible, en devenant candidate-donneuse d\u2019ovocytes. \u00c0 quelles conditions une candidate-donneuse d\u2019ovocytes doit-elle r\u00e9pondre ? En tant que candidate-donneuse, vous devez remplir un certain nombre de conditions : Vous [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":319,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-321","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Candidate-donneuse d\u2019ovocytes ? \u00c9tapes | Je porte bonheur<\/title>\n<meta name=\"description\" content=\"Vous souhaitez aider des couples infertiles \u00e0 devenir parents ? Devenez candidate-donneuse d\u2019ovocytes. Offrez-leur un miracle. Plus d\u2019informations ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Candidate-donneuse d\u2019ovocytes ? \u00c9tapes | Je porte bonheur\" \/>\n<meta property=\"og:description\" content=\"Vous souhaitez aider des couples infertiles \u00e0 devenir parents ? Devenez candidate-donneuse d\u2019ovocytes. Offrez-leur un miracle. Plus d\u2019informations ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/\" \/>\n<meta property=\"og:site_name\" content=\"Ik geef geluk\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-20T11:20:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/\",\"url\":\"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/\",\"name\":\"Candidate-donneuse d\u2019ovocytes ? \u00c9tapes | Je porte bonheur\",\"isPartOf\":{\"@id\":\"https:\/\/ikgeefgeluk.be\/#website\"},\"datePublished\":\"2018-03-15T08:52:11+00:00\",\"dateModified\":\"2020-04-20T11:20:54+00:00\",\"description\":\"Vous souhaitez aider des couples infertiles \u00e0 devenir parents ? Devenez candidate-donneuse d\u2019ovocytes. Offrez-leur un miracle. Plus d\u2019informations ?\",\"breadcrumb\":{\"@id\":\"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ikgeefgeluk.be\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidate ?\",\"item\":\"https:\/\/ikgeefgeluk.be\/fr\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Candidate-donneuse d&rsquo;ovocytes ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ikgeefgeluk.be\/#website\",\"url\":\"https:\/\/ikgeefgeluk.be\/\",\"name\":\"Ik geef geluk\",\"description\":\"Eiceldonatie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ikgeefgeluk.be\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Candidate-donneuse d\u2019ovocytes ? \u00c9tapes | Je porte bonheur","description":"Vous souhaitez aider des couples infertiles \u00e0 devenir parents ? Devenez candidate-donneuse d\u2019ovocytes. Offrez-leur un miracle. Plus d\u2019informations ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/","og_locale":"fr_FR","og_type":"article","og_title":"Candidate-donneuse d\u2019ovocytes ? \u00c9tapes | Je porte bonheur","og_description":"Vous souhaitez aider des couples infertiles \u00e0 devenir parents ? Devenez candidate-donneuse d\u2019ovocytes. Offrez-leur un miracle. Plus d\u2019informations ?","og_url":"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/","og_site_name":"Ik geef geluk","article_modified_time":"2020-04-20T11:20:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/","url":"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/","name":"Candidate-donneuse d\u2019ovocytes ? \u00c9tapes | Je porte bonheur","isPartOf":{"@id":"https:\/\/ikgeefgeluk.be\/#website"},"datePublished":"2018-03-15T08:52:11+00:00","dateModified":"2020-04-20T11:20:54+00:00","description":"Vous souhaitez aider des couples infertiles \u00e0 devenir parents ? Devenez candidate-donneuse d\u2019ovocytes. Offrez-leur un miracle. Plus d\u2019informations ?","breadcrumb":{"@id":"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ikgeefgeluk.be\/fr\/candidate\/candidate-donneuse-dovocytes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ikgeefgeluk.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Candidate ?","item":"https:\/\/ikgeefgeluk.be\/fr\/candidate\/"},{"@type":"ListItem","position":3,"name":"Candidate-donneuse d&rsquo;ovocytes ?"}]},{"@type":"WebSite","@id":"https:\/\/ikgeefgeluk.be\/#website","url":"https:\/\/ikgeefgeluk.be\/","name":"Ik geef geluk","description":"Eiceldonatie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ikgeefgeluk.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/ikgeefgeluk.be\/fr\/wp-json\/wp\/v2\/pages\/321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ikgeefgeluk.be\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ikgeefgeluk.be\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ikgeefgeluk.be\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ikgeefgeluk.be\/fr\/wp-json\/wp\/v2\/comments?post=321"}],"version-history":[{"count":45,"href":"https:\/\/ikgeefgeluk.be\/fr\/wp-json\/wp\/v2\/pages\/321\/revisions"}],"predecessor-version":[{"id":719,"href":"https:\/\/ikgeefgeluk.be\/fr\/wp-json\/wp\/v2\/pages\/321\/revisions\/719"}],"up":[{"embeddable":true,"href":"https:\/\/ikgeefgeluk.be\/fr\/wp-json\/wp\/v2\/pages\/319"}],"wp:attachment":[{"href":"https:\/\/ikgeefgeluk.be\/fr\/wp-json\/wp\/v2\/media?parent=321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}